{"id":115175,"date":"2024-12-16T16:40:03","date_gmt":"2024-12-16T15:40:03","guid":{"rendered":"https:\/\/gentedebasquet.com.ar\/sitio\/?p=115175"},"modified":"2024-12-16T16:40:03","modified_gmt":"2024-12-16T15:40:03","slug":"duba-es-campeon-del-tna-y-subio-a-primera","status":"publish","type":"post","link":"https:\/\/gentedebasquet.com.ar\/sitio\/2024\/12\/16\/duba-es-campeon-del-tna-y-subio-a-primera\/","title":{"rendered":"DUBa es campe\u00f3n del TNA y subi\u00f3 a Primera"},"content":{"rendered":"<p><b>En la primera semana de octubre se realiz\u00f3 en Bah\u00eda Blanca una semifinal del Torneo Nacional de Ascenso del basquet sobre silla de ruedas, que tuvo como participantes a DUBa, Jujuy Basquet y CEDIMA. Los dos primeros obtuvieron un pase a la gran final del campeonato. Por haber sido el de mejores promedios de puntos a favor y en contra el equipo de nuestra ciudad se gan\u00f3 el derecho de organizar esa etapa definitoria. Y eso hizo entre el 14 y 15 de diciembre pasados, cuando en el Polideportivo Norte de la calle Vieytes jug\u00f3 contra los juje\u00f1os, Municipalidad de Ensenada y CRiGaL (R\u00edo Gallegos).<\/b><\/p>\n<p><strong>Todos los juegos en estas fechas determinantes de diciembre en el Polideportivo fueron dirigidos por los \u00e1rbitros Alberto Ebensperger y Cristian Colombati.<\/strong><\/p>\n<p><strong>DUBa disput\u00f3 tres partidos en este cuadrangular final, y los gan\u00f3 todos. Al finalizar el segundo de esos encuentros, el s\u00e1bado a la noche, el equipo que conduce como DT Walter Mele ya sab\u00eda que su primer objetivo estaba logrado: ascender a la primera divisi\u00f3n. Ensenada y CRiGaL tambien obtuvieron su lugar en la pr\u00f3xima temporada de la m\u00e1xima categor\u00eda del pa\u00eds. Jujuy no pudo ganar partidos en este fin de semana y deber\u00e1 seguir en el TNA.<\/strong><\/p>\n<p><strong>Para el domingo solo quedaba un enfrentamiento y otra gran ilusi\u00f3n, asegurar el primer puesto y celebrarlo frente al numeroso p\u00fablico local que le puso color y aliento al estadio en cada jornada. En el \u00faltimo partido el rival fue CRiGaL (Club R\u00edo Gallegos de Lisiados), el otro equipo que tambien hab\u00eda ganado sus dos duelos del s\u00e1bado.\u00a0<\/strong><\/p>\n<p><strong>Este fue un partido en el que Discapacitados Unidos Bahienses no se sinti\u00f3 c\u00f3modo durante sus primeros minutos, pero que con el correr del tiempo logr\u00f3 dominar, liberandose de las defensas y avanzando r\u00e1pido para definir de contraataque.<\/strong><\/p>\n<p><strong>El s\u00e1bado 14 a las 11 de la ma\u00f1ana DUBa jug\u00f3 su primer partido de esta final. Su rival fue Municipalidad de Ensenada, el equipo al que los bahienses m\u00e1s enfrentaron en la temporada, por cuestiones de cercan\u00eda geogr\u00e1fica y organizaci\u00f3n de competencia. A continuaci\u00f3n dejamos la s\u00edntesis de ese partido:<\/strong><\/p>\n<p><strong>DUBa 47 :\u00a0<\/strong>Lucas Lagos 2; Daniel Plotequer 21; Julio Echavarr\u00eda 2; Pedro Saez; Rodolfo Coronel 10\u00a0<strong>(F.I.)\u00a0<\/strong>Alejandro Sanhueza; Leonardo Sarra\u00faa 6; Daiana Alfaro; Juan Ganga; Uriel General; Sergio Vera Peralta 4; Carlos Geldres.\u00a0<strong>DT:\u00a0<\/strong>Walter Mele.<\/p>\n<p><strong>Ensenada 42 :\u00a0<\/strong>Leandro C\u00e9spedes 5; Mateo Dom\u00ednguez 5; Diego Imas 14; Jazm\u00edn Sallis 8; Diego Rojas 8\u00a0<strong>(F.I.)\u00a0<\/strong>Brian Marsiglia; Mauricio Pardo; Facundo Di Paolo; Carlos Cilano; Juan D\u00edaz 2; Gustavo Gasparini; Dami\u00e1n Iborra.\u00a0<strong>DT:\u00a0<\/strong>Cristian G\u00f3mez.<\/p>\n<p><strong>Parciales:\u00a0<\/strong>10-4; 22-18 (12-14); 34-32 (12-14); 47-42 (13-10).<\/p>\n<p><strong>En la noche de ese mismo s\u00e1bado DUBa debi\u00f3 enfrentar a Jujuy Basquet. Las estad\u00edsticas de ese frente a frente fueron las siguientes:<\/strong><\/p>\n<p><strong>DUBa 50 : <\/strong>Lucas Lagos; Daniel Plotequer 16; Julio Echavarr\u00eda 6; Pedro Saez; Rodolfo Coronel 3 <strong>(F.I.)\u00a0<\/strong>Alejandro Sanhueza; Leonardo Sarra\u00faa 4; Daiana Alfaro 2; Juan Ganga; Uriel General; Sergio Vera Peralta 19; Carlos Geldres. <strong>DT:\u00a0<\/strong>Walter Mele.<\/p>\n<p><strong>Jujuy 34:\u00a0<\/strong>Jonatan Guanuco 2; Le\u00f3n Apaza 5; Iv\u00e1n Ju\u00e1rez C\u00f3rdoba 4; Dante Segovia 2; Luis Jim\u00e9nez 10 <strong>(F.I.)\u00a0<\/strong>Jair Cort\u00e9z; Facundo D\u00edaz 3; Eduardo Amadeo Morales; Alejo Landriel; V\u00edctor Ru\u00edz 8.\u00a0<strong>DT:\u00a0<\/strong>Gustavo Lemos.<\/p>\n<p><strong>Parciales:\u00a0<\/strong>10-7; 27-17 (17-10); 39-25 (12-8); 50-34 (11-9).<\/p>\n<p><strong>El \u00faltimo choque de este \u00faltimo fin de semana fue el que enfrent\u00f3 a DUBa con CRiGaL. Los bahienses salieron con la mente puesta en levantar el trofeo de campe\u00f3n y esa firme determinaci\u00f3n qued\u00f3 plasmada en la cancha: nuestro representante gan\u00f3 78 a 36. Abajo les dejamos la s\u00edntesis y un video con jugadas destacadas de ese partido y escenas de la entrega de trofeos y medallas y los festejos que coronaron este momento tan especial.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>DUBa 78 : <\/strong>Lucas Lagos 10; Daniel Plotequer 38; Julio Echavarr\u00eda 6; Pedro Saez 3; Rodolfo Coronel 4 <strong>(F.I.)\u00a0<\/strong>Alejandro Sanhueza; Leonardo Sarra\u00faa 2; Daiana Alfaro; Juan Ganga; Uriel General 2; Sergio Vera Peralta 13; Carlos Geldres. <strong>DT:\u00a0<\/strong>Walter Mele.<\/p>\n<p><strong>CRiGaL 36 : <\/strong>Cristian Torres 6; Marcos Rosas Ulloa; Luis Corzo; Luciano Dalla Fontana 11; Luciano Andrade <strong>(F.I.)\u00a0<\/strong>Jorge G\u00f3mez 3; Crist\u00f3bal Campa\u00f1a; Gloria Vivas.\u00a0<strong>DT:\u00a0<\/strong>Luciano Dalla Fontana.<\/p>\n<p><strong>Parciales:\u00a0<\/strong>7-7; 33-18 (26-11); 59-27 (26-9); 78-36 (19-9).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0\u00a0<\/strong><\/p>\n<div class=\"jeg_video_container jeg_video_content\">\n<p>&nbsp;<\/p>\n<div class=\"jeg_video_container jeg_video_content\"><iframe loading=\"lazy\" title=\"#TNA - Cuadrangular final - Juego 3 : DUBa 78 - 36 CRiGaL\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/ovC4glWXCEE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-115176 \" src=\"http:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2024\/12\/vlcsnap-2024-12-16-08h19m58s374-300x169.png\" alt=\"\" width=\"662\" height=\"373\" srcset=\"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2024\/12\/vlcsnap-2024-12-16-08h19m58s374-300x169.png 300w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2024\/12\/vlcsnap-2024-12-16-08h19m58s374-1024x576.png 1024w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2024\/12\/vlcsnap-2024-12-16-08h19m58s374-768x432.png 768w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2024\/12\/vlcsnap-2024-12-16-08h19m58s374-1536x864.png 1536w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2024\/12\/vlcsnap-2024-12-16-08h19m58s374-750x422.png 750w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2024\/12\/vlcsnap-2024-12-16-08h19m58s374-1140x641.png 1140w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2024\/12\/vlcsnap-2024-12-16-08h19m58s374.png 1920w\" sizes=\"(max-width: 662px) 100vw, 662px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la primera semana de octubre se realiz\u00f3 en Bah\u00eda Blanca una semifinal del Torneo Nacional de Ascenso del basquet sobre silla de ruedas, que tuvo como participantes a DUBa, Jujuy Basquet y CEDIMA. Los dos primeros obtuvieron un pase a la gran final del campeonato. Por haber sido el de mejores promedios de puntos [&hellip;]<\/p>\n","protected":false},"author":70,"featured_media":115177,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"1","single_blog_custom":"","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"0","show_view_counter":"0","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"0","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"0","number_popup_post":"1","show_author_box":"0","show_post_related":"0","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":"","hide":""},"jnews_social_meta":[],"jnews_override_counter":[],"footnotes":""},"categories":[1894,101],"tags":[2017,675,2018,1981],"class_list":["post-115175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-duba","category-slide","tag-crigal","tag-duba","tag-jujuy-basquet","tag-municipalidad-de-ensenada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DUBa es campe\u00f3n del TNA y subi\u00f3 a Primera - Gente de B\u00e1squet<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/gentedebasquet.com.ar\/sitio\/2024\/12\/16\/duba-es-campeon-del-tna-y-subio-a-primera\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DUBa es campe\u00f3n del TNA y subi\u00f3 a Primera - Gente de B\u00e1squet\" \/>\n<meta property=\"og:description\" content=\"En la primera semana de octubre se realiz\u00f3 en Bah\u00eda Blanca una semifinal del Torneo Nacional de Ascenso del basquet sobre silla de ruedas, que tuvo como participantes a DUBa, Jujuy Basquet y CEDIMA. Los dos primeros obtuvieron un pase a la gran final del campeonato. Por haber sido el de mejores promedios de puntos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/gentedebasquet.com.ar\/sitio\/2024\/12\/16\/duba-es-campeon-del-tna-y-subio-a-primera\/\" \/>\n<meta property=\"og:site_name\" content=\"Gente de B\u00e1squet\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-16T15:40:03+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2024\/12\/vlcsnap-2024-12-16-08h29m11s097.png\" \/>\n\t<meta property=\"og:image:width\" content=\"690\" \/>\n\t<meta property=\"og:image:height\" content=\"319\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Andres Camarero\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andres Camarero\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2024\\\/12\\\/16\\\/duba-es-campeon-del-tna-y-subio-a-primera\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2024\\\/12\\\/16\\\/duba-es-campeon-del-tna-y-subio-a-primera\\\/\"},\"author\":{\"name\":\"Andres Camarero\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#\\\/schema\\\/person\\\/6f3e5bc5df127b420a445d22fc9eaa51\"},\"headline\":\"DUBa es campe\u00f3n del TNA y subi\u00f3 a Primera\",\"datePublished\":\"2024-12-16T15:40:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2024\\\/12\\\/16\\\/duba-es-campeon-del-tna-y-subio-a-primera\\\/\"},\"wordCount\":729,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2024\\\/12\\\/16\\\/duba-es-campeon-del-tna-y-subio-a-primera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/vlcsnap-2024-12-16-08h29m11s097.png\",\"keywords\":[\"CRiGaL\",\"DUBA\",\"Jujuy Basquet\",\"Municipalidad de Ensenada\"],\"articleSection\":[\"DUBa\",\"Slide\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2024\\\/12\\\/16\\\/duba-es-campeon-del-tna-y-subio-a-primera\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2024\\\/12\\\/16\\\/duba-es-campeon-del-tna-y-subio-a-primera\\\/\",\"url\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2024\\\/12\\\/16\\\/duba-es-campeon-del-tna-y-subio-a-primera\\\/\",\"name\":\"DUBa es campe\u00f3n del TNA y subi\u00f3 a Primera - Gente de B\u00e1squet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2024\\\/12\\\/16\\\/duba-es-campeon-del-tna-y-subio-a-primera\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2024\\\/12\\\/16\\\/duba-es-campeon-del-tna-y-subio-a-primera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/vlcsnap-2024-12-16-08h29m11s097.png\",\"datePublished\":\"2024-12-16T15:40:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#\\\/schema\\\/person\\\/6f3e5bc5df127b420a445d22fc9eaa51\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2024\\\/12\\\/16\\\/duba-es-campeon-del-tna-y-subio-a-primera\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2024\\\/12\\\/16\\\/duba-es-campeon-del-tna-y-subio-a-primera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2024\\\/12\\\/16\\\/duba-es-campeon-del-tna-y-subio-a-primera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/vlcsnap-2024-12-16-08h29m11s097.png\",\"contentUrl\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/vlcsnap-2024-12-16-08h29m11s097.png\",\"width\":690,\"height\":319},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2024\\\/12\\\/16\\\/duba-es-campeon-del-tna-y-subio-a-primera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DUBa es campe\u00f3n del TNA y subi\u00f3 a Primera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/\",\"name\":\"Gente de B\u00e1squet\",\"description\":\"La revista del basquet de Bah\u00eda Blanca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#\\\/schema\\\/person\\\/6f3e5bc5df127b420a445d22fc9eaa51\",\"name\":\"Andres Camarero\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d4884ec54a50c25ccd5e4f54f5e904d09dfe74ef58e58f631f3917b6fed7cd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d4884ec54a50c25ccd5e4f54f5e904d09dfe74ef58e58f631f3917b6fed7cd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d4884ec54a50c25ccd5e4f54f5e904d09dfe74ef58e58f631f3917b6fed7cd?s=96&d=mm&r=g\",\"caption\":\"Andres Camarero\"},\"url\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/author\\\/andres-camarero\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DUBa es campe\u00f3n del TNA y subi\u00f3 a Primera - Gente de B\u00e1squet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/gentedebasquet.com.ar\/sitio\/2024\/12\/16\/duba-es-campeon-del-tna-y-subio-a-primera\/","og_locale":"es_ES","og_type":"article","og_title":"DUBa es campe\u00f3n del TNA y subi\u00f3 a Primera - Gente de B\u00e1squet","og_description":"En la primera semana de octubre se realiz\u00f3 en Bah\u00eda Blanca una semifinal del Torneo Nacional de Ascenso del basquet sobre silla de ruedas, que tuvo como participantes a DUBa, Jujuy Basquet y CEDIMA. Los dos primeros obtuvieron un pase a la gran final del campeonato. Por haber sido el de mejores promedios de puntos [&hellip;]","og_url":"http:\/\/gentedebasquet.com.ar\/sitio\/2024\/12\/16\/duba-es-campeon-del-tna-y-subio-a-primera\/","og_site_name":"Gente de B\u00e1squet","article_published_time":"2024-12-16T15:40:03+00:00","og_image":[{"width":690,"height":319,"url":"http:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2024\/12\/vlcsnap-2024-12-16-08h29m11s097.png","type":"image\/png"}],"author":"Andres Camarero","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andres Camarero","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2024\/12\/16\/duba-es-campeon-del-tna-y-subio-a-primera\/#article","isPartOf":{"@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2024\/12\/16\/duba-es-campeon-del-tna-y-subio-a-primera\/"},"author":{"name":"Andres Camarero","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#\/schema\/person\/6f3e5bc5df127b420a445d22fc9eaa51"},"headline":"DUBa es campe\u00f3n del TNA y subi\u00f3 a Primera","datePublished":"2024-12-16T15:40:03+00:00","mainEntityOfPage":{"@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2024\/12\/16\/duba-es-campeon-del-tna-y-subio-a-primera\/"},"wordCount":729,"commentCount":0,"image":{"@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2024\/12\/16\/duba-es-campeon-del-tna-y-subio-a-primera\/#primaryimage"},"thumbnailUrl":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2024\/12\/vlcsnap-2024-12-16-08h29m11s097.png","keywords":["CRiGaL","DUBA","Jujuy Basquet","Municipalidad de Ensenada"],"articleSection":["DUBa","Slide"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/gentedebasquet.com.ar\/sitio\/2024\/12\/16\/duba-es-campeon-del-tna-y-subio-a-primera\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2024\/12\/16\/duba-es-campeon-del-tna-y-subio-a-primera\/","url":"http:\/\/gentedebasquet.com.ar\/sitio\/2024\/12\/16\/duba-es-campeon-del-tna-y-subio-a-primera\/","name":"DUBa es campe\u00f3n del TNA y subi\u00f3 a Primera - Gente de B\u00e1squet","isPartOf":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#website"},"primaryImageOfPage":{"@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2024\/12\/16\/duba-es-campeon-del-tna-y-subio-a-primera\/#primaryimage"},"image":{"@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2024\/12\/16\/duba-es-campeon-del-tna-y-subio-a-primera\/#primaryimage"},"thumbnailUrl":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2024\/12\/vlcsnap-2024-12-16-08h29m11s097.png","datePublished":"2024-12-16T15:40:03+00:00","author":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#\/schema\/person\/6f3e5bc5df127b420a445d22fc9eaa51"},"breadcrumb":{"@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2024\/12\/16\/duba-es-campeon-del-tna-y-subio-a-primera\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/gentedebasquet.com.ar\/sitio\/2024\/12\/16\/duba-es-campeon-del-tna-y-subio-a-primera\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2024\/12\/16\/duba-es-campeon-del-tna-y-subio-a-primera\/#primaryimage","url":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2024\/12\/vlcsnap-2024-12-16-08h29m11s097.png","contentUrl":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2024\/12\/vlcsnap-2024-12-16-08h29m11s097.png","width":690,"height":319},{"@type":"BreadcrumbList","@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2024\/12\/16\/duba-es-campeon-del-tna-y-subio-a-primera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/gentedebasquet.com.ar\/sitio\/"},{"@type":"ListItem","position":2,"name":"DUBa es campe\u00f3n del TNA y subi\u00f3 a Primera"}]},{"@type":"WebSite","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#website","url":"https:\/\/gentedebasquet.com.ar\/sitio\/","name":"Gente de B\u00e1squet","description":"La revista del basquet de Bah\u00eda Blanca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gentedebasquet.com.ar\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#\/schema\/person\/6f3e5bc5df127b420a445d22fc9eaa51","name":"Andres Camarero","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f6d4884ec54a50c25ccd5e4f54f5e904d09dfe74ef58e58f631f3917b6fed7cd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f6d4884ec54a50c25ccd5e4f54f5e904d09dfe74ef58e58f631f3917b6fed7cd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f6d4884ec54a50c25ccd5e4f54f5e904d09dfe74ef58e58f631f3917b6fed7cd?s=96&d=mm&r=g","caption":"Andres Camarero"},"url":"https:\/\/gentedebasquet.com.ar\/sitio\/author\/andres-camarero\/"}]}},"_links":{"self":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/115175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/users\/70"}],"replies":[{"embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=115175"}],"version-history":[{"count":3,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/115175\/revisions"}],"predecessor-version":[{"id":115180,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/115175\/revisions\/115180"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/media\/115177"}],"wp:attachment":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=115175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=115175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=115175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}