{"id":120799,"date":"2026-04-14T06:03:19","date_gmt":"2026-04-14T04:03:19","guid":{"rendered":"https:\/\/gentedebasquet.com.ar\/sitio\/?p=120799"},"modified":"2026-04-14T06:03:19","modified_gmt":"2026-04-14T04:03:19","slug":"uno-de-los-buenos-estudiantes-ahora-es-escolta","status":"publish","type":"post","link":"https:\/\/gentedebasquet.com.ar\/sitio\/2026\/04\/14\/uno-de-los-buenos-estudiantes-ahora-es-escolta\/","title":{"rendered":"Uno de los buenos Estudiantes ahora es escolta"},"content":{"rendered":"<p><strong>Estudiantes volvi\u00f3 al triunfo en casa<\/strong> ante Independiente y <strong>es uno de los escoltas de Napost\u00e1<\/strong> en el Torneo de Primera. <strong>Fue victoria 91-82 en un dur\u00edsimo duelo<\/strong>, en el que el \u00abAlbo\u00bb pudo dominar el juego en el segundo tiempo, con un <strong>gran trabajo en la pintura de Jorge Garc\u00eda y Alan Gonz\u00e1lez.<\/strong><\/p>\n<p><strong>Empez\u00f3 mejor el \u00abViola\u00bb<\/strong>, con un par de bombas de Lucho Figueroa. Intercambiaron golpes en el primer cuarto, se prestaron la ventaja en el marcador y no encontraron diferencias mayores a 4 puntos.<strong> Fue de alto goleo y transiciones r\u00e1pidas, arriba la visita 22-23.<\/strong><\/p>\n<p><strong>En el segundo tom\u00f3 cierto vuelo el conjunto dirigido por Javier Musumeci<\/strong>. Con Figueroa y Formiga como cartas ofensivas, logr\u00f3 ponerse 23-30 y 27-35, pero Estudiantes siempre volv\u00eda, con el juego interno de Garc\u00eda, Gonz\u00e1lez y Belleggia como lo m\u00e1s rendidor. <strong>El visitante toc\u00f3 la m\u00e1xima de 10 (32-42)<\/strong> pero el local la fue limando hasta cerrar el primer tiempo 43-47.<\/p>\n<p>A la vuelta del descanso largo, los de Facundo Sastre tuvieron un <strong>parcial 7-2 para pasar al frente.<\/strong> All\u00ed se volvi\u00f3 parejo nuevamente, jugaron al golpe por golpe, se prestaron la delantera en el luminoso, y <strong>Estudiantes termin\u00f3 arriba apenas por la m\u00ednima<\/strong>, 67-66.<\/p>\n<p>En los \u00faltimos diez minutos, <strong>el local pareci\u00f3 tener m\u00e1s piernas<\/strong>, en el inicio logr\u00f3 sacar +5, hubo un par de jugadas de 2+1 de Alan Gonz\u00e1lez, e Independiente empez\u00f3 a perder hombres por acumulaci\u00f3n de faltas. La diferencia fue corta, hubo imprecisiones y promediando el segmento, estuvieron un minuto y medio sin anotar. <strong>El \u00abAlbo\u00bb sac\u00f3 6 de ventaja a dos minutos del final<\/strong> y as\u00ed cerr\u00f3 el juego un poco m\u00e1s holgado.<\/p>\n<p><strong>Gan\u00f3 Estudiantes<\/strong>, se recuper\u00f3 de la derrota ante Barrio Hospital, y es uno de los escoltas del campeonato. Por su parte, <strong>Independiente igual\u00f3 su r\u00e9cord<\/strong> en 2-2, en lo que fue<strong> otro partido competitivo<\/strong> del equipo de Musumeci.<\/p>\n<div class=\"jeg_video_container jeg_video_content\"><iframe loading=\"lazy\" title=\"#Primera - Fecha #4: Estudiantes 91 - 82 Independiente\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/PCHcoKiMtu0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-120800\" src=\"http:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/CLAVE-estudiantes-300x300.png\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/CLAVE-estudiantes-300x300.png 300w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/CLAVE-estudiantes-1024x1024.png 1024w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/CLAVE-estudiantes-150x150.png 150w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/CLAVE-estudiantes-768x768.png 768w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/CLAVE-estudiantes-1536x1536.png 1536w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/CLAVE-estudiantes-75x75.png 75w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/CLAVE-estudiantes-350x350.png 350w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/CLAVE-estudiantes-750x750.png 750w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/CLAVE-estudiantes-1140x1140.png 1140w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/CLAVE-estudiantes.png 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-120809\" src=\"http:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-14-at-00.52.02-2-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-14-at-00.52.02-2-300x225.jpeg 300w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-14-at-00.52.02-2-1024x768.jpeg 1024w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-14-at-00.52.02-2-768x576.jpeg 768w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-14-at-00.52.02-2-750x563.jpeg 750w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-14-at-00.52.02-2-1140x855.jpeg 1140w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-14-at-00.52.02-2.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<blockquote><p>\u00abEn el segundo tiempo defendimos m\u00e1s fuerte, m\u00e1s intenso, quer\u00edamos plasmar lo que mostramos con Pac\u00edfico, queremos ir por ese camino, defender y correr. El trabajo de todos los d\u00edas es importante, todos los partidos son parejos. No queremos ponernos metas, vamos partido a partido. La idea del t\u00e9cnico sigue la de Ariel (Ugolini) pero planteando su estilo, tenemos que seguir trabajando.\u00bb, <strong>Jorge Garc\u00eda, Estudiantes.<\/strong><\/p><\/blockquote>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-120801\" src=\"http:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/MVP-garcia-300x300.png\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/MVP-garcia-300x300.png 300w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/MVP-garcia-1024x1024.png 1024w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/MVP-garcia-150x150.png 150w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/MVP-garcia-768x768.png 768w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/MVP-garcia-1536x1536.png 1536w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/MVP-garcia-75x75.png 75w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/MVP-garcia-350x350.png 350w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/MVP-garcia-750x750.png 750w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/MVP-garcia-1140x1140.png 1140w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/MVP-garcia.png 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><strong>S\u00edntesis &#8211; Primera Divisi\u00f3n &#8211; Fecha 4<\/strong><\/p>\n<p><strong>Estudiantes 91:<\/strong> Juli\u00e1n Rodr\u00edguez 11, Octavio Cancellarich 5, Lucas Delgado 10, <em><strong>Jorge Garc\u00eda 22<\/strong><\/em>, Alan Gonz\u00e1lez 15 <strong>(FI);<\/strong> Santiago Ruesga 9, Francisco Mazzello 1, Luca Storni 4, Lisandro Bl\u00e1zquez 0, Jos\u00e9 Belleggia 14. <strong>DT: Facundo Sastre.<\/strong><\/p>\n<p><strong>Independiente 82:<\/strong> Mart\u00edn Schmir 2, Juli\u00e1n Ripoll 15 (x), Ignacio Formiga 8, Alen R\u00edos 17 (x), Luciano Figueroa 11 <strong>(FI);<\/strong> Juan Pablo Mor\u00e1n 6, Facundo Slonimsqui 1, Fernando Bonino 7, Maximiliano Zonza 15. <strong>DT: Javier Musumeci.<\/strong><\/p>\n<p><strong>Cuartos:<\/strong> 22-23, 43-47 (21-24), 67-66 (24-19), 91-82 (24-16)<\/p>\n<p><strong>\u00c1rbitros:<\/strong> Mariano Enrique &#8211; Horacio Sed\u00e1n &#8211; Juan Jaramillo<\/p>\n<p><strong>Cancha:<\/strong> Osvaldo Casanova (Estudiantes)<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-120810 size-large\" src=\"http:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-14-at-00.52.02-1-1024x576.jpeg\" alt=\"\" width=\"1024\" height=\"576\" srcset=\"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-14-at-00.52.02-1-1024x576.jpeg 1024w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-14-at-00.52.02-1-300x169.jpeg 300w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-14-at-00.52.02-1-768x432.jpeg 768w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-14-at-00.52.02-1-750x422.jpeg 750w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-14-at-00.52.02-1-1140x641.jpeg 1140w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-14-at-00.52.02-1.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estudiantes volvi\u00f3 al triunfo en casa ante Independiente y es uno de los escoltas de Napost\u00e1 en el Torneo de Primera. Fue victoria 91-82 en un dur\u00edsimo duelo, en el que el \u00abAlbo\u00bb pudo dominar el juego en el segundo tiempo, con un gran trabajo en la pintura de Jorge Garc\u00eda y Alan Gonz\u00e1lez. Empez\u00f3 [&hellip;]<\/p>\n","protected":false},"author":71,"featured_media":120811,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"footnotes":""},"categories":[23,101],"tags":[11,12,89,1169,508],"class_list":["post-120799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primera","category-slide","tag-estudiantes","tag-independiente","tag-jorge-garcia","tag-primera","tag-primera-division"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uno de los buenos Estudiantes ahora es escolta - Gente de B\u00e1squet<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gentedebasquet.com.ar\/sitio\/2026\/04\/14\/uno-de-los-buenos-estudiantes-ahora-es-escolta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uno de los buenos Estudiantes ahora es escolta - Gente de B\u00e1squet\" \/>\n<meta property=\"og:description\" content=\"Estudiantes volvi\u00f3 al triunfo en casa ante Independiente y es uno de los escoltas de Napost\u00e1 en el Torneo de Primera. Fue victoria 91-82 en un dur\u00edsimo duelo, en el que el \u00abAlbo\u00bb pudo dominar el juego en el segundo tiempo, con un gran trabajo en la pintura de Jorge Garc\u00eda y Alan Gonz\u00e1lez. Empez\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gentedebasquet.com.ar\/sitio\/2026\/04\/14\/uno-de-los-buenos-estudiantes-ahora-es-escolta\/\" \/>\n<meta property=\"og:site_name\" content=\"Gente de B\u00e1squet\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-14T04:03:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-14-at-00.52.02.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Santiago Seisdedos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Santiago Seisdedos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2026\\\/04\\\/14\\\/uno-de-los-buenos-estudiantes-ahora-es-escolta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2026\\\/04\\\/14\\\/uno-de-los-buenos-estudiantes-ahora-es-escolta\\\/\"},\"author\":{\"name\":\"Santiago Seisdedos\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#\\\/schema\\\/person\\\/3b50d7c801b9529aba70bd4613bca6da\"},\"headline\":\"Uno de los buenos Estudiantes ahora es escolta\",\"datePublished\":\"2026-04-14T04:03:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2026\\\/04\\\/14\\\/uno-de-los-buenos-estudiantes-ahora-es-escolta\\\/\"},\"wordCount\":499,\"image\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2026\\\/04\\\/14\\\/uno-de-los-buenos-estudiantes-ahora-es-escolta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/WhatsApp-Image-2026-04-14-at-00.52.02.jpeg\",\"keywords\":[\"Estudiantes\",\"independiente\",\"Jorge Garc\u00eda\",\"Primera\",\"Primera Divisi\u00f3n\"],\"articleSection\":[\"Primera\",\"Slide\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2026\\\/04\\\/14\\\/uno-de-los-buenos-estudiantes-ahora-es-escolta\\\/\",\"url\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2026\\\/04\\\/14\\\/uno-de-los-buenos-estudiantes-ahora-es-escolta\\\/\",\"name\":\"Uno de los buenos Estudiantes ahora es escolta - Gente de B\u00e1squet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2026\\\/04\\\/14\\\/uno-de-los-buenos-estudiantes-ahora-es-escolta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2026\\\/04\\\/14\\\/uno-de-los-buenos-estudiantes-ahora-es-escolta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/WhatsApp-Image-2026-04-14-at-00.52.02.jpeg\",\"datePublished\":\"2026-04-14T04:03:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#\\\/schema\\\/person\\\/3b50d7c801b9529aba70bd4613bca6da\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2026\\\/04\\\/14\\\/uno-de-los-buenos-estudiantes-ahora-es-escolta\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2026\\\/04\\\/14\\\/uno-de-los-buenos-estudiantes-ahora-es-escolta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2026\\\/04\\\/14\\\/uno-de-los-buenos-estudiantes-ahora-es-escolta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/WhatsApp-Image-2026-04-14-at-00.52.02.jpeg\",\"contentUrl\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/WhatsApp-Image-2026-04-14-at-00.52.02.jpeg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2026\\\/04\\\/14\\\/uno-de-los-buenos-estudiantes-ahora-es-escolta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uno de los buenos Estudiantes ahora es escolta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/\",\"name\":\"Gente de B\u00e1squet\",\"description\":\"La revista del basquet de Bah\u00eda Blanca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#\\\/schema\\\/person\\\/3b50d7c801b9529aba70bd4613bca6da\",\"name\":\"Santiago Seisdedos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be737e74404eb3825c4679da7a152b3c6980b470f7253114cd451344e20a8d80?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be737e74404eb3825c4679da7a152b3c6980b470f7253114cd451344e20a8d80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be737e74404eb3825c4679da7a152b3c6980b470f7253114cd451344e20a8d80?s=96&d=mm&r=g\",\"caption\":\"Santiago Seisdedos\"},\"url\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/author\\\/santiago-sesidedos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uno de los buenos Estudiantes ahora es escolta - Gente de B\u00e1squet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gentedebasquet.com.ar\/sitio\/2026\/04\/14\/uno-de-los-buenos-estudiantes-ahora-es-escolta\/","og_locale":"es_ES","og_type":"article","og_title":"Uno de los buenos Estudiantes ahora es escolta - Gente de B\u00e1squet","og_description":"Estudiantes volvi\u00f3 al triunfo en casa ante Independiente y es uno de los escoltas de Napost\u00e1 en el Torneo de Primera. Fue victoria 91-82 en un dur\u00edsimo duelo, en el que el \u00abAlbo\u00bb pudo dominar el juego en el segundo tiempo, con un gran trabajo en la pintura de Jorge Garc\u00eda y Alan Gonz\u00e1lez. Empez\u00f3 [&hellip;]","og_url":"https:\/\/gentedebasquet.com.ar\/sitio\/2026\/04\/14\/uno-de-los-buenos-estudiantes-ahora-es-escolta\/","og_site_name":"Gente de B\u00e1squet","article_published_time":"2026-04-14T04:03:19+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-14-at-00.52.02.jpeg","type":"image\/jpeg"}],"author":"Santiago Seisdedos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Santiago Seisdedos","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2026\/04\/14\/uno-de-los-buenos-estudiantes-ahora-es-escolta\/#article","isPartOf":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2026\/04\/14\/uno-de-los-buenos-estudiantes-ahora-es-escolta\/"},"author":{"name":"Santiago Seisdedos","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#\/schema\/person\/3b50d7c801b9529aba70bd4613bca6da"},"headline":"Uno de los buenos Estudiantes ahora es escolta","datePublished":"2026-04-14T04:03:19+00:00","mainEntityOfPage":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2026\/04\/14\/uno-de-los-buenos-estudiantes-ahora-es-escolta\/"},"wordCount":499,"image":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2026\/04\/14\/uno-de-los-buenos-estudiantes-ahora-es-escolta\/#primaryimage"},"thumbnailUrl":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-14-at-00.52.02.jpeg","keywords":["Estudiantes","independiente","Jorge Garc\u00eda","Primera","Primera Divisi\u00f3n"],"articleSection":["Primera","Slide"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2026\/04\/14\/uno-de-los-buenos-estudiantes-ahora-es-escolta\/","url":"https:\/\/gentedebasquet.com.ar\/sitio\/2026\/04\/14\/uno-de-los-buenos-estudiantes-ahora-es-escolta\/","name":"Uno de los buenos Estudiantes ahora es escolta - Gente de B\u00e1squet","isPartOf":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2026\/04\/14\/uno-de-los-buenos-estudiantes-ahora-es-escolta\/#primaryimage"},"image":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2026\/04\/14\/uno-de-los-buenos-estudiantes-ahora-es-escolta\/#primaryimage"},"thumbnailUrl":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-14-at-00.52.02.jpeg","datePublished":"2026-04-14T04:03:19+00:00","author":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#\/schema\/person\/3b50d7c801b9529aba70bd4613bca6da"},"breadcrumb":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2026\/04\/14\/uno-de-los-buenos-estudiantes-ahora-es-escolta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gentedebasquet.com.ar\/sitio\/2026\/04\/14\/uno-de-los-buenos-estudiantes-ahora-es-escolta\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2026\/04\/14\/uno-de-los-buenos-estudiantes-ahora-es-escolta\/#primaryimage","url":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-14-at-00.52.02.jpeg","contentUrl":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-14-at-00.52.02.jpeg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2026\/04\/14\/uno-de-los-buenos-estudiantes-ahora-es-escolta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/gentedebasquet.com.ar\/sitio\/"},{"@type":"ListItem","position":2,"name":"Uno de los buenos Estudiantes ahora es escolta"}]},{"@type":"WebSite","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#website","url":"https:\/\/gentedebasquet.com.ar\/sitio\/","name":"Gente de B\u00e1squet","description":"La revista del basquet de Bah\u00eda Blanca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gentedebasquet.com.ar\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#\/schema\/person\/3b50d7c801b9529aba70bd4613bca6da","name":"Santiago Seisdedos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/be737e74404eb3825c4679da7a152b3c6980b470f7253114cd451344e20a8d80?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/be737e74404eb3825c4679da7a152b3c6980b470f7253114cd451344e20a8d80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/be737e74404eb3825c4679da7a152b3c6980b470f7253114cd451344e20a8d80?s=96&d=mm&r=g","caption":"Santiago Seisdedos"},"url":"https:\/\/gentedebasquet.com.ar\/sitio\/author\/santiago-sesidedos\/"}]}},"_links":{"self":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/120799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/users\/71"}],"replies":[{"embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=120799"}],"version-history":[{"count":5,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/120799\/revisions"}],"predecessor-version":[{"id":120816,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/120799\/revisions\/120816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/media\/120811"}],"wp:attachment":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=120799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=120799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=120799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}