{"id":19618,"date":"2013-11-21T00:01:50","date_gmt":"2013-11-21T00:01:50","guid":{"rendered":"http:\/\/www.gentedebasquet.com.ar\/?p=19618"},"modified":"2013-11-21T00:01:50","modified_gmt":"2013-11-21T00:01:50","slug":"sin-prisa-pero-sin-pausa","status":"publish","type":"post","link":"https:\/\/gentedebasquet.com.ar\/sitio\/2013\/11\/21\/sin-prisa-pero-sin-pausa\/","title":{"rendered":"Sin prisa pero sin pausa"},"content":{"rendered":"<p><em><strong><a href=\"http:\/\/www.gentedebasquet.com.ar\/wp-content\/uploads\/2013\/11\/BOS2.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-19623\" title=\"Spurs Celtics\" src=\"http:\/\/www.gentedebasquet.com.ar\/wp-content\/uploads\/2013\/11\/BOS2.jpg\" alt=\"\" width=\"448\" height=\"336\" \/><\/a>San Antonio venci\u00f3 a Boston y sigue l\u00edder de la Conferencia Oeste con una sola ca\u00edda en diez presentaciones. Fue 104 a 93, con 5 puntos y 6 asistencias de \u00abManu\u00bb Gin\u00f3bili. Parker fue el goleador de los Spurs con 19. El viernes el equipo texano visita a Memphis.<!--more--><\/strong><\/em><\/p>\n<p>Los Spurs contin\u00faan siendo uno de los dos mejores conjuntos en el comienzo de la temporada NBA. Junto a Indiana \u00a0Pacers (Este), equipo en el que milita Luis Scola, registra un r\u00e9cord de 10-1 para liderar su conferencia, la Oeste.<\/p>\n<p>En su \u00faltima presentaci\u00f3n, San Antonio venci\u00f3 como local a Boston Celtics 104 a 93, con buena actuaci\u00f3n de Emanuel Gin\u00f3bili y goleo repartido.<\/p>\n<p>El bahiense cerr\u00f3 su planilla con 5 puntos (1\/1 3p, 1\/4 2p), 3 rebotes, 6 asistencias, 1 robo, 1 bloqueo y 1 falta personal en 24m00s de acci\u00f3n.<\/p>\n<p>En tanto, el m\u00e1ximo anotador texano fue Tony Parker, con 19. Lo siguieron Kawhi Leonard (16, 8 recobres y 5 robos), Tim Duncan (13 y 9 rebotes), Boris Diaw (12), Danny Green (11) y Tiago Splitter (11 y 10 tableros).<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/Q6JCdB4hUnA\" frameborder=\"0\" width=\"560\" height=\"315\"><\/iframe><\/p>\n<p><em>Agenda de San Antonio:<\/em><\/p>\n<p>&#8211; Viernes 22\/11 vs Memphis Grizzlies (V)<\/p>\n<p>&#8211; S\u00e1bado 23\/11 vs Cleveland Cavaliers (L)<\/p>\n<p>&#8211; Lunes 25\/11 vs New Orleans Pelicans (L)<\/p>\n<p>&#8211; Mi\u00e9rcoles 27\/11 vs Oklahoma City Thunder (V)<\/p>\n<p>&#8211; Viernes 29\/11 vs Orlando Magic (V)<\/p>\n<p>Fuente: NBA.com, @InfoManu y @spurs.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>San Antonio venci\u00f3 a Boston y sigue l\u00edder de la Conferencia Oeste con una sola ca\u00edda en diez presentaciones. Fue 104 a 93, con 5 puntos y 6 asistencias de \u00abManu\u00bb Gin\u00f3bili. Parker fue el goleador de los Spurs con 19. El viernes el equipo texano visita a Memphis.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"footnotes":""},"categories":[34],"tags":[],"class_list":["post-19618","post","type-post","status-publish","format-standard","hentry","category-bahienses-afuera"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sin prisa pero sin pausa - Gente de B\u00e1squet<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/gentedebasquet.com.ar\/sitio\/2013\/11\/21\/sin-prisa-pero-sin-pausa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sin prisa pero sin pausa - Gente de B\u00e1squet\" \/>\n<meta property=\"og:description\" content=\"San Antonio venci\u00f3 a Boston y sigue l\u00edder de la Conferencia Oeste con una sola ca\u00edda en diez presentaciones. Fue 104 a 93, con 5 puntos y 6 asistencias de \u00abManu\u00bb Gin\u00f3bili. Parker fue el goleador de los Spurs con 19. El viernes el equipo texano visita a Memphis.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/gentedebasquet.com.ar\/sitio\/2013\/11\/21\/sin-prisa-pero-sin-pausa\/\" \/>\n<meta property=\"og:site_name\" content=\"Gente de B\u00e1squet\" \/>\n<meta property=\"article:published_time\" content=\"2013-11-21T00:01:50+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.gentedebasquet.com.ar\/wp-content\/uploads\/2013\/11\/BOS2.jpg\" \/>\n<meta name=\"author\" content=\"Gente de B\u00e1squet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gente de B\u00e1squet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2013\\\/11\\\/21\\\/sin-prisa-pero-sin-pausa\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2013\\\/11\\\/21\\\/sin-prisa-pero-sin-pausa\\\/\"},\"author\":{\"name\":\"Gente de B\u00e1squet\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#\\\/schema\\\/person\\\/ca0b63bbb977369988a7bbbdc519943a\"},\"headline\":\"Sin prisa pero sin pausa\",\"datePublished\":\"2013-11-21T00:01:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2013\\\/11\\\/21\\\/sin-prisa-pero-sin-pausa\\\/\"},\"wordCount\":216,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2013\\\/11\\\/21\\\/sin-prisa-pero-sin-pausa\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.gentedebasquet.com.ar\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/BOS2.jpg\",\"articleSection\":[\"Bahienses Afuera\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2013\\\/11\\\/21\\\/sin-prisa-pero-sin-pausa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2013\\\/11\\\/21\\\/sin-prisa-pero-sin-pausa\\\/\",\"url\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2013\\\/11\\\/21\\\/sin-prisa-pero-sin-pausa\\\/\",\"name\":\"Sin prisa pero sin pausa - Gente de B\u00e1squet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2013\\\/11\\\/21\\\/sin-prisa-pero-sin-pausa\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2013\\\/11\\\/21\\\/sin-prisa-pero-sin-pausa\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.gentedebasquet.com.ar\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/BOS2.jpg\",\"datePublished\":\"2013-11-21T00:01:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#\\\/schema\\\/person\\\/ca0b63bbb977369988a7bbbdc519943a\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2013\\\/11\\\/21\\\/sin-prisa-pero-sin-pausa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2013\\\/11\\\/21\\\/sin-prisa-pero-sin-pausa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2013\\\/11\\\/21\\\/sin-prisa-pero-sin-pausa\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.gentedebasquet.com.ar\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/BOS2.jpg\",\"contentUrl\":\"http:\\\/\\\/www.gentedebasquet.com.ar\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/BOS2.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2013\\\/11\\\/21\\\/sin-prisa-pero-sin-pausa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sin prisa pero sin pausa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/\",\"name\":\"Gente de B\u00e1squet\",\"description\":\"La revista del basquet de Bah\u00eda Blanca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#\\\/schema\\\/person\\\/ca0b63bbb977369988a7bbbdc519943a\",\"name\":\"Gente de B\u00e1squet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"caption\":\"Gente de B\u00e1squet\"},\"sameAs\":[\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\"],\"url\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/author\\\/ulises\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sin prisa pero sin pausa - Gente de B\u00e1squet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/gentedebasquet.com.ar\/sitio\/2013\/11\/21\/sin-prisa-pero-sin-pausa\/","og_locale":"es_ES","og_type":"article","og_title":"Sin prisa pero sin pausa - Gente de B\u00e1squet","og_description":"San Antonio venci\u00f3 a Boston y sigue l\u00edder de la Conferencia Oeste con una sola ca\u00edda en diez presentaciones. Fue 104 a 93, con 5 puntos y 6 asistencias de \u00abManu\u00bb Gin\u00f3bili. Parker fue el goleador de los Spurs con 19. El viernes el equipo texano visita a Memphis.","og_url":"http:\/\/gentedebasquet.com.ar\/sitio\/2013\/11\/21\/sin-prisa-pero-sin-pausa\/","og_site_name":"Gente de B\u00e1squet","article_published_time":"2013-11-21T00:01:50+00:00","og_image":[{"url":"http:\/\/www.gentedebasquet.com.ar\/wp-content\/uploads\/2013\/11\/BOS2.jpg","type":"","width":"","height":""}],"author":"Gente de B\u00e1squet","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gente de B\u00e1squet","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2013\/11\/21\/sin-prisa-pero-sin-pausa\/#article","isPartOf":{"@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2013\/11\/21\/sin-prisa-pero-sin-pausa\/"},"author":{"name":"Gente de B\u00e1squet","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#\/schema\/person\/ca0b63bbb977369988a7bbbdc519943a"},"headline":"Sin prisa pero sin pausa","datePublished":"2013-11-21T00:01:50+00:00","mainEntityOfPage":{"@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2013\/11\/21\/sin-prisa-pero-sin-pausa\/"},"wordCount":216,"commentCount":0,"image":{"@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2013\/11\/21\/sin-prisa-pero-sin-pausa\/#primaryimage"},"thumbnailUrl":"http:\/\/www.gentedebasquet.com.ar\/wp-content\/uploads\/2013\/11\/BOS2.jpg","articleSection":["Bahienses Afuera"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/gentedebasquet.com.ar\/sitio\/2013\/11\/21\/sin-prisa-pero-sin-pausa\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2013\/11\/21\/sin-prisa-pero-sin-pausa\/","url":"http:\/\/gentedebasquet.com.ar\/sitio\/2013\/11\/21\/sin-prisa-pero-sin-pausa\/","name":"Sin prisa pero sin pausa - Gente de B\u00e1squet","isPartOf":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#website"},"primaryImageOfPage":{"@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2013\/11\/21\/sin-prisa-pero-sin-pausa\/#primaryimage"},"image":{"@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2013\/11\/21\/sin-prisa-pero-sin-pausa\/#primaryimage"},"thumbnailUrl":"http:\/\/www.gentedebasquet.com.ar\/wp-content\/uploads\/2013\/11\/BOS2.jpg","datePublished":"2013-11-21T00:01:50+00:00","author":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#\/schema\/person\/ca0b63bbb977369988a7bbbdc519943a"},"breadcrumb":{"@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2013\/11\/21\/sin-prisa-pero-sin-pausa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/gentedebasquet.com.ar\/sitio\/2013\/11\/21\/sin-prisa-pero-sin-pausa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2013\/11\/21\/sin-prisa-pero-sin-pausa\/#primaryimage","url":"http:\/\/www.gentedebasquet.com.ar\/wp-content\/uploads\/2013\/11\/BOS2.jpg","contentUrl":"http:\/\/www.gentedebasquet.com.ar\/wp-content\/uploads\/2013\/11\/BOS2.jpg"},{"@type":"BreadcrumbList","@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2013\/11\/21\/sin-prisa-pero-sin-pausa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/gentedebasquet.com.ar\/sitio\/"},{"@type":"ListItem","position":2,"name":"Sin prisa pero sin pausa"}]},{"@type":"WebSite","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#website","url":"https:\/\/gentedebasquet.com.ar\/sitio\/","name":"Gente de B\u00e1squet","description":"La revista del basquet de Bah\u00eda Blanca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gentedebasquet.com.ar\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#\/schema\/person\/ca0b63bbb977369988a7bbbdc519943a","name":"Gente de B\u00e1squet","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","caption":"Gente de B\u00e1squet"},"sameAs":["http:\/\/gentedebasquet.com.ar\/sitio"],"url":"https:\/\/gentedebasquet.com.ar\/sitio\/author\/ulises\/"}]}},"_links":{"self":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/19618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=19618"}],"version-history":[{"count":0,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/19618\/revisions"}],"wp:attachment":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=19618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=19618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=19618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}