{"id":21944,"date":"2014-02-07T16:51:42","date_gmt":"2014-02-07T16:51:42","guid":{"rendered":"http:\/\/www.gentedebasquet.com.ar\/?p=21944"},"modified":"2014-02-07T16:51:42","modified_gmt":"2014-02-07T16:51:42","slug":"la-maldicion-de-los-lideres","status":"publish","type":"post","link":"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/07\/la-maldicion-de-los-lideres\/","title":{"rendered":"La maldici\u00f3n de los l\u00edderes"},"content":{"rendered":"<p><em><strong><a href=\"http:\/\/www.gentedebasquet.com.ar\/wp-content\/uploads\/2014\/02\/Torres-Maca\u00e9-Paulistano.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-21945\" title=\"Torres Maca\u00e9 Paulistano\" src=\"http:\/\/www.gentedebasquet.com.ar\/wp-content\/uploads\/2014\/02\/Torres-Maca\u00e9-Paulistano.jpg\" alt=\"\" width=\"448\" height=\"336\" \/><\/a>Maca\u00e9 cay\u00f3 ante Paulistano 110 a 93 con 7 puntos y 5 rebotes en 18 minutos de Juan Manuel Torres. As\u00ed, contin\u00faa sin poder ganar un juego ante los primeros 7 equipos de la liga brasilera: Flamengo, Pinheiros (2), Limeira, Paulistano (2), S\u00e3o Jos\u00e9, Uniceub y Uberlandia.<!--more--><\/strong><\/em><\/p>\n<p>Maca\u00e9 Basquete realiz\u00f3 una buena primera mitad (se fue al descanso arriba 49 a 41) pero baj\u00f3 el rendimiento en la segunda parte, permiti\u00f3 69 puntos y termin\u00f3 perdiendo ante Paulistano por 110 a 93.<\/p>\n<p>El pivot bahiense <strong>Juan Manuel Torre<\/strong>s sum\u00f3 7 unidades (3\/4 2p, 1\/1 TL9, 5 rebotes y 3 faltas personales en 17m52. Por su parte, el compatriota Pablo Espinoza, recientemente electo para el Juego de las Estrellas, aport\u00f3 18 puntos, 8 recobres, 4 asistencias y 4 robos en 32m02.<\/p>\n<p>Torres promedia 8.9 puntos, 4.2 rebotes y 0.95 asistencias en 21.7 minutos en Maca\u00e9, equipo que se ubica 13\u00ba en las posiciones, con r\u00e9cord de 7 victorias y 14 derrotas.<\/p>\n<p><span style=\"color: #ffcc99;\">.<\/span><\/p>\n<p><strong>Sergio Santos Hern\u00e1ndez<\/strong><\/p>\n<p><em>Agenda de Uniceub:<\/em><\/p>\n<p>&#8211; Liga de las Am\u00e9ricas (7, 8 y 9\/02)<\/p>\n<p>&#8211; 15\/02 vs Goiania (L)<\/p>\n<p>&#8211; 18\/02 vs Uberlandia (L)<\/p>\n<p>&#8211; 25\/02 vs Pinheiros (V)<\/p>\n<p>&#8211; 27\/02 vs Palmeiras (V)<\/p>\n<p><strong>Juan Manuel Torres<\/strong><\/p>\n<p><em>Agenda de Maca\u00e9:<\/em><\/p>\n<p>&#8211; 08\/02 vs Liga Sorocabana (V)<\/p>\n<p>&#8211; 13\/02 vs\u00a0Esp\u00edrito Santo (L)<\/p>\n<p>&#8211; 15\/02 vs Minas (L)<\/p>\n<p>&#8211; 25\/02 vs Sao Jos\u00e9 (V)<\/p>\n<p>&#8211; 06\/03 vs Bauru (L)<\/p>\n<p><strong>Fuente:<\/strong>\u00a0NBB.<\/p>\n<p><strong>Foto:<\/strong>\u00a0Ale da Costa (NBB).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maca\u00e9 cay\u00f3 ante Paulistano 110 a 93 con 7 puntos y 5 rebotes en 18 minutos de Juan Manuel Torres. As\u00ed, contin\u00faa sin poder ganar un juego ante los primeros 7 equipos de la liga brasilera: Flamengo, Pinheiros (2), Limeira, Paulistano (2), S\u00e3o Jos\u00e9, Uniceub y Uberlandia.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"footnotes":""},"categories":[34],"tags":[],"class_list":["post-21944","post","type-post","status-publish","format-standard","hentry","category-bahienses-afuera"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La maldici\u00f3n de los l\u00edderes - Gente de B\u00e1squet<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/07\/la-maldicion-de-los-lideres\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La maldici\u00f3n de los l\u00edderes - Gente de B\u00e1squet\" \/>\n<meta property=\"og:description\" content=\"Maca\u00e9 cay\u00f3 ante Paulistano 110 a 93 con 7 puntos y 5 rebotes en 18 minutos de Juan Manuel Torres. As\u00ed, contin\u00faa sin poder ganar un juego ante los primeros 7 equipos de la liga brasilera: Flamengo, Pinheiros (2), Limeira, Paulistano (2), S\u00e3o Jos\u00e9, Uniceub y Uberlandia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/07\/la-maldicion-de-los-lideres\/\" \/>\n<meta property=\"og:site_name\" content=\"Gente de B\u00e1squet\" \/>\n<meta property=\"article:published_time\" content=\"2014-02-07T16:51:42+00:00\" \/>\n<meta name=\"author\" content=\"Gente de B\u00e1squet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gente de B\u00e1squet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2014\\\/02\\\/07\\\/la-maldicion-de-los-lideres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2014\\\/02\\\/07\\\/la-maldicion-de-los-lideres\\\/\"},\"author\":{\"name\":\"Gente de B\u00e1squet\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#\\\/schema\\\/person\\\/ca0b63bbb977369988a7bbbdc519943a\"},\"headline\":\"La maldici\u00f3n de los l\u00edderes\",\"datePublished\":\"2014-02-07T16:51:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2014\\\/02\\\/07\\\/la-maldicion-de-los-lideres\\\/\"},\"wordCount\":208,\"commentCount\":0,\"articleSection\":[\"Bahienses Afuera\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2014\\\/02\\\/07\\\/la-maldicion-de-los-lideres\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2014\\\/02\\\/07\\\/la-maldicion-de-los-lideres\\\/\",\"url\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2014\\\/02\\\/07\\\/la-maldicion-de-los-lideres\\\/\",\"name\":\"La maldici\u00f3n de los l\u00edderes - Gente de B\u00e1squet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#website\"},\"datePublished\":\"2014-02-07T16:51:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#\\\/schema\\\/person\\\/ca0b63bbb977369988a7bbbdc519943a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2014\\\/02\\\/07\\\/la-maldicion-de-los-lideres\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2014\\\/02\\\/07\\\/la-maldicion-de-los-lideres\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2014\\\/02\\\/07\\\/la-maldicion-de-los-lideres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La maldici\u00f3n de los l\u00edderes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/\",\"name\":\"Gente de B\u00e1squet\",\"description\":\"La revista del basquet de Bah\u00eda Blanca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#\\\/schema\\\/person\\\/ca0b63bbb977369988a7bbbdc519943a\",\"name\":\"Gente de B\u00e1squet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"caption\":\"Gente de B\u00e1squet\"},\"sameAs\":[\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\"],\"url\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/author\\\/ulises\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La maldici\u00f3n de los l\u00edderes - Gente de B\u00e1squet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/07\/la-maldicion-de-los-lideres\/","og_locale":"es_ES","og_type":"article","og_title":"La maldici\u00f3n de los l\u00edderes - Gente de B\u00e1squet","og_description":"Maca\u00e9 cay\u00f3 ante Paulistano 110 a 93 con 7 puntos y 5 rebotes en 18 minutos de Juan Manuel Torres. As\u00ed, contin\u00faa sin poder ganar un juego ante los primeros 7 equipos de la liga brasilera: Flamengo, Pinheiros (2), Limeira, Paulistano (2), S\u00e3o Jos\u00e9, Uniceub y Uberlandia.","og_url":"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/07\/la-maldicion-de-los-lideres\/","og_site_name":"Gente de B\u00e1squet","article_published_time":"2014-02-07T16:51:42+00:00","author":"Gente de B\u00e1squet","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gente de B\u00e1squet","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/07\/la-maldicion-de-los-lideres\/#article","isPartOf":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/07\/la-maldicion-de-los-lideres\/"},"author":{"name":"Gente de B\u00e1squet","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#\/schema\/person\/ca0b63bbb977369988a7bbbdc519943a"},"headline":"La maldici\u00f3n de los l\u00edderes","datePublished":"2014-02-07T16:51:42+00:00","mainEntityOfPage":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/07\/la-maldicion-de-los-lideres\/"},"wordCount":208,"commentCount":0,"articleSection":["Bahienses Afuera"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/07\/la-maldicion-de-los-lideres\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/07\/la-maldicion-de-los-lideres\/","url":"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/07\/la-maldicion-de-los-lideres\/","name":"La maldici\u00f3n de los l\u00edderes - Gente de B\u00e1squet","isPartOf":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#website"},"datePublished":"2014-02-07T16:51:42+00:00","author":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#\/schema\/person\/ca0b63bbb977369988a7bbbdc519943a"},"breadcrumb":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/07\/la-maldicion-de-los-lideres\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/07\/la-maldicion-de-los-lideres\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/07\/la-maldicion-de-los-lideres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/gentedebasquet.com.ar\/sitio\/"},{"@type":"ListItem","position":2,"name":"La maldici\u00f3n de los l\u00edderes"}]},{"@type":"WebSite","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#website","url":"https:\/\/gentedebasquet.com.ar\/sitio\/","name":"Gente de B\u00e1squet","description":"La revista del basquet de Bah\u00eda Blanca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gentedebasquet.com.ar\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#\/schema\/person\/ca0b63bbb977369988a7bbbdc519943a","name":"Gente de B\u00e1squet","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","caption":"Gente de B\u00e1squet"},"sameAs":["http:\/\/gentedebasquet.com.ar\/sitio"],"url":"https:\/\/gentedebasquet.com.ar\/sitio\/author\/ulises\/"}]}},"_links":{"self":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/21944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=21944"}],"version-history":[{"count":0,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/21944\/revisions"}],"wp:attachment":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=21944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=21944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=21944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}