{"id":22389,"date":"2014-02-19T03:31:10","date_gmt":"2014-02-19T03:31:10","guid":{"rendered":"http:\/\/www.gentedebasquet.com.ar\/?p=22389"},"modified":"2014-02-19T03:31:10","modified_gmt":"2014-02-19T03:31:10","slug":"con-paciencia-aurinegra","status":"publish","type":"post","link":"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/19\/con-paciencia-aurinegra\/","title":{"rendered":"Con paciencia Aurinegra"},"content":{"rendered":"<p><em><strong>Olimpo tuvo que batallar contra un duro Napost\u00e1 durante tres cuartos, para reci\u00e9n en el \u00faltimo sacar diferencias y quedarse con la victoria. Fue por 83 a 66 con un Gast\u00f3n Ressia imparable (22 puntos con 10\/13 T2) m\u00e1s el aporte de Victoria y S\u00e1nchez con 15 y 12 tantos respectivamente. En el conjunto de calle Alem se destacaron Augusto Menezes con 18 unidades y Tajan con 15.<!--more--><\/strong><\/em><\/p>\n<p>El primer parcial comenz\u00f3 favorable a Olimpo, que con la conducci\u00f3n de Ruesga m\u00e1s el aporte interno de Agust\u00edn S\u00e1nchez le permit\u00edan romper la defensa de Napo y conseguir dobles c\u00f3modos para estar al frente 9 a 3. Sin embargo los de Bonis reaccionaron, achicaban diferencias y r\u00e1pidamente se pusieron en juego, para pasar al frente por primera vez en el marcador 19 a 17 a 1m10s del final con 7 puntos de Augusto Menezes.<\/p>\n<p>En el segundo cuarto los de Allende salieron con todo y con un parcial de 7 a 2 en poco menos de dos minutos volvieron a pasar al frente en el marcador. Ressia era la carta de gol en el aurinegro, aportando 10 de sus 22 puntos en este pasaje. Napost\u00e1 por su parte rotaba el banco y no consegu\u00eda que Bellozas y Campa\u00f1a entraran en juego y deb\u00eda repartir sus puntos y hasta lleg\u00f3 a quedar con un equipo bajo en cancha. Olimpo se iba al descanso largo 42 a 35 arriba.<\/p>\n<p>A la vuelta de los vestuarios fue Napost\u00e1 el que empezaba mejor, que con un parcial de 5 a 0 se pon\u00eda a tan solo dos puntos. Pero comenzaba a crecer la figura de Victoria, el alero aportaba 5 puntos seguidos y volv\u00eda a estirar la brecha. As\u00ed transcurr\u00eda el tercer cuarto, Olimpo sacaba una luz de diferencia y Napo contrarrestaba hasta que llegaron al \u00faltimo descanso 59 a 53 a favor de los de \u00c1ngel Brunel.<\/p>\n<p>Dos triples de Victoria, m\u00e1s dos libres de Ressia le permit\u00edan a Olimpo sacar 15 puntos en el comienzo del \u00faltimo periodo. De ah\u00ed en adelante fue todo del aurinegro que lleg\u00f3 a sacar la m\u00e1xima diferencia del juego (18) a mitad de cuarto. Los de Bonis trataron de reaccionar y hacer menor la diferencia, pero fue imposible, el auri manejo con tranquilidad los hilos de los minutos finales y Napo no estaba fino con la punter\u00eda.<\/p>\n<p><span style=\"color: #ffcc99;\">.<\/span><\/p>\n<p><span style=\"text-decoration: underline;\"><em><strong>S\u00edntesis:<\/strong><\/em><\/span><\/p>\n<p><strong>Olimpo 83:<\/strong><\/p>\n<p>Iniciales: Franco Ruesga (10); Gast\u00f3n Ressia (22); Cristian Victoria (15); Marcos Fern\u00e1ndez (4) y Agust\u00edn S\u00e1nchez (12).<\/p>\n<p>Ingresaron: Juan Ignacio Carini (2); Federico Montenegro (0); Lahuel Silva (2); Facundo Arens (9); Genaro Priore (0); Lucas Luchetti (7) y Ezequiel Zani (0).<\/p>\n<p>DT: Daniel Allende.<\/p>\n<p><strong>Napost\u00e1 66:<\/strong><\/p>\n<p>Iniciales: Ezequiel Menezes (6); Ramiro Aguirre (5), Juan Igancio Bellozas (6); Augusto Meneses (18) y Mauro Campa\u00f1a (3).<\/p>\n<p>Ingresaron: Ignacio Luppino (3); Bruno Pallotti (3); Juan Di Meglio (5); Iturrioz (2) y Tajan (15).<\/p>\n<p>DT: Luciano Bonis.<\/p>\n<p><span style=\"color: #ffcc99;\">.<\/span><\/p>\n<p><strong>Parciales:<\/strong> Olimpo 21-22, 42-35 (21-13), 59-53 (17-18) y 83-66 (24-13).<\/p>\n<p><strong>Cinco faltas:<\/strong> Agust\u00edn S\u00e1nchez (O).<\/p>\n<p><strong>Jueces:<\/strong> Jorge Scheffer y Diego Kessler.<\/p>\n<p><strong>Estadio:<\/strong> Hermanos Ciccioli, El Nacional.<\/p>\n<p><a class=\"modalfiframe\" title=\"Planilla\" href=\"https:\/\/docs.google.com\/spreadsheet\/pub?key=0ApvEEwl0g9-EdHEtZTVxZHpWYmdZbnlDUzJJS3BxS1E&amp;output=html\">Ver Planilla<\/a><\/p>\n<p><strong>Foto:<\/strong> Romina Sald\u00edas.<\/p>\n<p><span style=\"color: #ffcc99;\">.<\/span><\/p>\n<p><strong>POSICIONES<\/strong><\/p>\n<p>Villa Mitre 6pts (3-0)<\/p>\n<p>El Nacional 5pts (2-1)<\/p>\n<p>Olimpo 5pts (2-1)<\/p>\n<p>Canterbury 4pts (1-2)<\/p>\n<p>Napost\u00e1 4pts (1-2)<\/p>\n<p>Estudiantes 3pts (0-3)<\/p>\n<p><span style=\"color: #ffcc99;\">.<\/span><\/p>\n<p><a href=\"http:\/\/www.gentedebasquet.com.ar\/wp-content\/uploads\/2014\/02\/Fixture-Basquetbol.jpg\"><img decoding=\"async\" alt=\"\" src=\"http:\/\/www.gentedebasquet.com.ar\/wp-content\/uploads\/2014\/02\/Fixture-Basquetbol.jpg\" width=\"679\" height=\"960\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Olimpo tuvo que batallar contra un duro Napost\u00e1 durante tres cuartos, para reci\u00e9n en el \u00faltimo sacar diferencias y quedarse con la victoria. Fue por 83 a 66 con un Gast\u00f3n Ressia imparable (22 puntos con 10\/13 T2) m\u00e1s el aporte de Victoria y S\u00e1nchez con 15 y 12 tantos respectivamente. En el conjunto de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25709,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"footnotes":""},"categories":[23],"tags":[15,16],"class_list":["post-22389","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primera","tag-naposta","tag-olimpo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Con paciencia Aurinegra - Gente de B\u00e1squet<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/19\/con-paciencia-aurinegra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Con paciencia Aurinegra - Gente de B\u00e1squet\" \/>\n<meta property=\"og:description\" content=\"Olimpo tuvo que batallar contra un duro Napost\u00e1 durante tres cuartos, para reci\u00e9n en el \u00faltimo sacar diferencias y quedarse con la victoria. Fue por 83 a 66 con un Gast\u00f3n Ressia imparable (22 puntos con 10\/13 T2) m\u00e1s el aporte de Victoria y S\u00e1nchez con 15 y 12 tantos respectivamente. En el conjunto de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/19\/con-paciencia-aurinegra\/\" \/>\n<meta property=\"og:site_name\" content=\"Gente de B\u00e1squet\" \/>\n<meta property=\"article:published_time\" content=\"2014-02-19T03:31:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2014\/01\/DSCN0626.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gente de B\u00e1squet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gente de B\u00e1squet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2014\\\/02\\\/19\\\/con-paciencia-aurinegra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2014\\\/02\\\/19\\\/con-paciencia-aurinegra\\\/\"},\"author\":{\"name\":\"Gente de B\u00e1squet\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#\\\/schema\\\/person\\\/ca0b63bbb977369988a7bbbdc519943a\"},\"headline\":\"Con paciencia Aurinegra\",\"datePublished\":\"2014-02-19T03:31:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2014\\\/02\\\/19\\\/con-paciencia-aurinegra\\\/\"},\"wordCount\":512,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2014\\\/02\\\/19\\\/con-paciencia-aurinegra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/DSCN0626.jpg\",\"keywords\":[\"Naposta\",\"Ol\u00edmpo\"],\"articleSection\":[\"Primera\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2014\\\/02\\\/19\\\/con-paciencia-aurinegra\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2014\\\/02\\\/19\\\/con-paciencia-aurinegra\\\/\",\"url\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2014\\\/02\\\/19\\\/con-paciencia-aurinegra\\\/\",\"name\":\"Con paciencia Aurinegra - Gente de B\u00e1squet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2014\\\/02\\\/19\\\/con-paciencia-aurinegra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2014\\\/02\\\/19\\\/con-paciencia-aurinegra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/DSCN0626.jpg\",\"datePublished\":\"2014-02-19T03:31:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#\\\/schema\\\/person\\\/ca0b63bbb977369988a7bbbdc519943a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2014\\\/02\\\/19\\\/con-paciencia-aurinegra\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2014\\\/02\\\/19\\\/con-paciencia-aurinegra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2014\\\/02\\\/19\\\/con-paciencia-aurinegra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/DSCN0626.jpg\",\"contentUrl\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/DSCN0626.jpg\",\"width\":300,\"height\":225},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2014\\\/02\\\/19\\\/con-paciencia-aurinegra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Con paciencia Aurinegra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/\",\"name\":\"Gente de B\u00e1squet\",\"description\":\"La revista del basquet de Bah\u00eda Blanca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#\\\/schema\\\/person\\\/ca0b63bbb977369988a7bbbdc519943a\",\"name\":\"Gente de B\u00e1squet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"caption\":\"Gente de B\u00e1squet\"},\"sameAs\":[\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\"],\"url\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/author\\\/ulises\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Con paciencia Aurinegra - Gente de B\u00e1squet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/19\/con-paciencia-aurinegra\/","og_locale":"es_ES","og_type":"article","og_title":"Con paciencia Aurinegra - Gente de B\u00e1squet","og_description":"Olimpo tuvo que batallar contra un duro Napost\u00e1 durante tres cuartos, para reci\u00e9n en el \u00faltimo sacar diferencias y quedarse con la victoria. Fue por 83 a 66 con un Gast\u00f3n Ressia imparable (22 puntos con 10\/13 T2) m\u00e1s el aporte de Victoria y S\u00e1nchez con 15 y 12 tantos respectivamente. En el conjunto de [&hellip;]","og_url":"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/19\/con-paciencia-aurinegra\/","og_site_name":"Gente de B\u00e1squet","article_published_time":"2014-02-19T03:31:10+00:00","og_image":[{"width":300,"height":225,"url":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2014\/01\/DSCN0626.jpg","type":"image\/jpeg"}],"author":"Gente de B\u00e1squet","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gente de B\u00e1squet","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/19\/con-paciencia-aurinegra\/#article","isPartOf":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/19\/con-paciencia-aurinegra\/"},"author":{"name":"Gente de B\u00e1squet","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#\/schema\/person\/ca0b63bbb977369988a7bbbdc519943a"},"headline":"Con paciencia Aurinegra","datePublished":"2014-02-19T03:31:10+00:00","mainEntityOfPage":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/19\/con-paciencia-aurinegra\/"},"wordCount":512,"commentCount":0,"image":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/19\/con-paciencia-aurinegra\/#primaryimage"},"thumbnailUrl":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2014\/01\/DSCN0626.jpg","keywords":["Naposta","Ol\u00edmpo"],"articleSection":["Primera"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/19\/con-paciencia-aurinegra\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/19\/con-paciencia-aurinegra\/","url":"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/19\/con-paciencia-aurinegra\/","name":"Con paciencia Aurinegra - Gente de B\u00e1squet","isPartOf":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/19\/con-paciencia-aurinegra\/#primaryimage"},"image":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/19\/con-paciencia-aurinegra\/#primaryimage"},"thumbnailUrl":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2014\/01\/DSCN0626.jpg","datePublished":"2014-02-19T03:31:10+00:00","author":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#\/schema\/person\/ca0b63bbb977369988a7bbbdc519943a"},"breadcrumb":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/19\/con-paciencia-aurinegra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/19\/con-paciencia-aurinegra\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/19\/con-paciencia-aurinegra\/#primaryimage","url":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2014\/01\/DSCN0626.jpg","contentUrl":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2014\/01\/DSCN0626.jpg","width":300,"height":225},{"@type":"BreadcrumbList","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2014\/02\/19\/con-paciencia-aurinegra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/gentedebasquet.com.ar\/sitio\/"},{"@type":"ListItem","position":2,"name":"Con paciencia Aurinegra"}]},{"@type":"WebSite","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#website","url":"https:\/\/gentedebasquet.com.ar\/sitio\/","name":"Gente de B\u00e1squet","description":"La revista del basquet de Bah\u00eda Blanca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gentedebasquet.com.ar\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#\/schema\/person\/ca0b63bbb977369988a7bbbdc519943a","name":"Gente de B\u00e1squet","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","caption":"Gente de B\u00e1squet"},"sameAs":["http:\/\/gentedebasquet.com.ar\/sitio"],"url":"https:\/\/gentedebasquet.com.ar\/sitio\/author\/ulises\/"}]}},"_links":{"self":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/22389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=22389"}],"version-history":[{"count":0,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/22389\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/media\/25709"}],"wp:attachment":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=22389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=22389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=22389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}