{"id":48821,"date":"2015-07-29T15:20:13","date_gmt":"2015-07-29T18:20:13","guid":{"rendered":"http:\/\/www.gentedebasquet.com.ar\/?p=48821"},"modified":"2015-07-29T15:20:13","modified_gmt":"2015-07-29T18:20:13","slug":"se-levanto-la-veda","status":"publish","type":"post","link":"https:\/\/gentedebasquet.com.ar\/sitio\/2015\/07\/29\/se-levanto-la-veda\/","title":{"rendered":"Se levant\u00f3 la veda"},"content":{"rendered":"<p><strong>Despu\u00e9s de una muy buena asamblea con la participaci\u00f3n de m\u00e1s de 80 jugadores y en reuni\u00f3n con dirigentes de la Asociaci\u00f3n de Clubes, se firm\u00f3 un acuerdo y se levant\u00f3 la veda contractual. Adem\u00e1s, qued\u00f3 establecido el contrato \u00fanico que regir\u00e1 en la A y TNA.\u00a0Luego de 4 horas de reuni\u00f3n en la sede de la Asociaci\u00f3n de Clubes, se firm\u00f3 un Acta Acuerdo entre los m\u00e1ximos responsables de la AdC y AdJ.\u00a0<\/strong><\/p>\n<p><span style=\"text-decoration: underline;\"><strong>El detalle a continuaci\u00f3n:\u00a0<\/strong><\/span><\/p>\n<p>En la Ciudad Aut\u00f3noma de Buenos Aires, a los 28 d\u00edas del mes de julio de 2015, siendo las 20.00 horas, en la sede de la Asociaci\u00f3n de Clubes de B\u00e1squetbol, se re\u00fanen las autoridades de la entidad, se\u00f1ores Fabi\u00e1n Borro, Gerardo Montenegro, N\u00e9stor Ch\u00e1ves, Andr\u00e9s Pelussi y Sergio Guerrero, conjuntamente con el letrado apoderado de la entidad, Dr. Daniel Wolanik, y las autoridades de la Asociaci\u00f3n de Jugadores y diversos integrantes de la misma, se\u00f1ores Mike Stura, Dr. Carlos Montesano, Paolo Quinteros, Mart\u00edn Leiva, Selem Safar, Diego Prego y Juli\u00e1n Olmedo, a efectos de celebrar el presente acta acuerdo, por el cual las partes convienen:<\/p>\n<p>Primero: Las partes, luego de un arduo debate, han consensuado el contrato \u00fanico que representa la voluntad de los integrantes de ambas entidades, el que comenzar\u00e1 a regir a partir del d\u00eda de la fecha. Dicho contrato es superador de los que se encontraban siendo suscriptos a la fecha y tiene como principal objetivo garantizar los derechos y obligaciones de los representados por ambas entidades, suscribi\u00e9ndose como anexo I el mismo.<\/p>\n<p>Segundo: Con relaci\u00f3n al petitorio presentado por la Asociaci\u00f3n de Jugadores, las partes han convenido:<\/p>\n<p>1. 8 fichas de mayores m\u00e1s 2 jugadores Sub 23 en la Liga A, con un m\u00e1ximo de 3 extranjeros optativos.<\/p>\n<p>2. 6 fichas de mayores en el TNA, m\u00e1s 1 Sub 23 y 1 Sub 21, con un m\u00e1ximo de 1 extranjero optativo.<\/p>\n<p>3. Fecha de presentaci\u00f3n de Libre Deuda hasta 30 d\u00edas posteriores a la finalizaci\u00f3n de cada competencia, habi\u00e9ndose fijado el d\u00eda 18 de agosto del corriente para la Liga Nacional y el 4 de agosto del corriente para el TNA.<\/p>\n<p>6. Competencia de 10 meses de duraci\u00f3n con pretemporada incluida. La Liga Nacional comenzar\u00e1 el d\u00eda 23 de septiembre del corriente y el TNA el 14 de octubre de 2015.<\/p>\n<p>7. Inicio de pretemporada hasta 40 d\u00edas previos al partido inaugural.<\/p>\n<p>8. Receso por Fiestas (sin entrenamientos, ni partidos) del 23 de diciembre al 2 de enero de 2016, inclusive.<\/p>\n<p>9. M\u00e1ximo de 3 (tres) partidos en gira, respetando 48 horas entre cada encuentro. Lo acordado podr\u00e1 ser afectado, en el caso que el club dispute torneos internacionales y deba jugar partidos reprogramados.<\/p>\n<p>10. Extremar las medidas para procurar se mantenga la misma cantidad de partidos disputados en los enfrentamientos entre equipos.<\/p>\n<p>11. Descanso de 36 horas sin actividad, posterior a giras de 3 (tres) partidos, contadas a partir del regreso del equipo a su ciudad de origen y un m\u00ednimo de 72 horas de plazo (luego de su gira) hasta la disputa del pr\u00f3ximo juego. Esto ser\u00e1 una atribuci\u00f3n de los entrenadores, comprometi\u00e9ndose las entidades firmantes en poner en conocimiento de la Asociaci\u00f3n de Clubes cualquier hecho que afecte el descanso de los jugadores para que se tomen las medidas que pudieran corresponder.<\/p>\n<p>12. En la Liga Nacional ser\u00e1 obligatorio contar con un kinesi\u00f3logo o fisioterapeuta permanente acompa\u00f1ando al equipo en entrenamientos, partidos de local y giras. En el TNA, el equipo local deber\u00e1 brindar una asistencia kinesiol\u00f3gica al equipo visitante y una red de contenci\u00f3n y\/o atenci\u00f3n de los mismos.<\/p>\n<p>13. Incluir en el calendario de la competencia el Juego de las Estrellas, organizado por la Asociaci\u00f3n de Jugadores.<\/p>\n<p>Tercero: Con el acuerdo arribado, la Asociaci\u00f3n de Jugadores deja sin efecto la veda de contrataci\u00f3n y en cumplimiento de la voluntad de sus asociados procede a la firma del presente acuerdo. La Asociaci\u00f3n de Clubes, en representaci\u00f3n de los Clubes afiliados y cumpliendo el mandato conferido a la Mesa Ejecutiva firma el presente acuerdo.<\/p>\n<p>Cuarto: Las partes continuar\u00e1n trabajando para instrumentar un plan de mejoras de infraestructura y log\u00edstica para las pr\u00f3ximas temporadas (viajes, hoteles, kinesiolog\u00eda en el TNA, etc).<\/p>\n<p>Siendo las 00.05 horas del d\u00eda 29 de julio de 2015 se firman dos ejemplares de un mismo tenor y al solo efecto, en el lugar y fecha denunciado precedentemente.<\/p>\n<p><strong>Fuente:<\/strong> Asociaci\u00f3n de Jugadores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se firm\u00f3 un Acta Acuerdo entre los m\u00e1ximos responsables de la AdC y AdJ<\/p>\n","protected":false},"author":1,"featured_media":48844,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"footnotes":""},"categories":[112,43,39],"tags":[376,377,78,121],"class_list":["post-48821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tna","category-la-liga","category-nacional","tag-adc","tag-adj","tag-lnb","tag-tna"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se levant\u00f3 la veda - Gente de B\u00e1squet<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/gentedebasquet.com.ar\/sitio\/2015\/07\/29\/se-levanto-la-veda\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se levant\u00f3 la veda - Gente de B\u00e1squet\" \/>\n<meta property=\"og:description\" content=\"Se firm\u00f3 un Acta Acuerdo entre los m\u00e1ximos responsables de la AdC y AdJ\" \/>\n<meta property=\"og:url\" content=\"http:\/\/gentedebasquet.com.ar\/sitio\/2015\/07\/29\/se-levanto-la-veda\/\" \/>\n<meta property=\"og:site_name\" content=\"Gente de B\u00e1squet\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-29T18:20:13+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2015\/07\/adj-300x211-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"211\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gente de B\u00e1squet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gente de B\u00e1squet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2015\\\/07\\\/29\\\/se-levanto-la-veda\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2015\\\/07\\\/29\\\/se-levanto-la-veda\\\/\"},\"author\":{\"name\":\"Gente de B\u00e1squet\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#\\\/schema\\\/person\\\/ca0b63bbb977369988a7bbbdc519943a\"},\"headline\":\"Se levant\u00f3 la veda\",\"datePublished\":\"2015-07-29T18:20:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2015\\\/07\\\/29\\\/se-levanto-la-veda\\\/\"},\"wordCount\":753,\"image\":{\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2015\\\/07\\\/29\\\/se-levanto-la-veda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/adj-300x211-1.jpg\",\"keywords\":[\"AdC\",\"ADJ\",\"LNB\",\"TNA\"],\"articleSection\":[\"Liga Argentina\",\"Liga Nacional\",\"Nacional\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2015\\\/07\\\/29\\\/se-levanto-la-veda\\\/\",\"url\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2015\\\/07\\\/29\\\/se-levanto-la-veda\\\/\",\"name\":\"Se levant\u00f3 la veda - Gente de B\u00e1squet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2015\\\/07\\\/29\\\/se-levanto-la-veda\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2015\\\/07\\\/29\\\/se-levanto-la-veda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/adj-300x211-1.jpg\",\"datePublished\":\"2015-07-29T18:20:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#\\\/schema\\\/person\\\/ca0b63bbb977369988a7bbbdc519943a\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2015\\\/07\\\/29\\\/se-levanto-la-veda\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2015\\\/07\\\/29\\\/se-levanto-la-veda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2015\\\/07\\\/29\\\/se-levanto-la-veda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/adj-300x211-1.jpg\",\"contentUrl\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/adj-300x211-1.jpg\",\"width\":300,\"height\":211},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2015\\\/07\\\/29\\\/se-levanto-la-veda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se levant\u00f3 la veda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/\",\"name\":\"Gente de B\u00e1squet\",\"description\":\"La revista del basquet de Bah\u00eda Blanca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#\\\/schema\\\/person\\\/ca0b63bbb977369988a7bbbdc519943a\",\"name\":\"Gente de B\u00e1squet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"caption\":\"Gente de B\u00e1squet\"},\"sameAs\":[\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\"],\"url\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/author\\\/ulises\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se levant\u00f3 la veda - Gente de B\u00e1squet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/gentedebasquet.com.ar\/sitio\/2015\/07\/29\/se-levanto-la-veda\/","og_locale":"es_ES","og_type":"article","og_title":"Se levant\u00f3 la veda - Gente de B\u00e1squet","og_description":"Se firm\u00f3 un Acta Acuerdo entre los m\u00e1ximos responsables de la AdC y AdJ","og_url":"http:\/\/gentedebasquet.com.ar\/sitio\/2015\/07\/29\/se-levanto-la-veda\/","og_site_name":"Gente de B\u00e1squet","article_published_time":"2015-07-29T18:20:13+00:00","og_image":[{"width":300,"height":211,"url":"http:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2015\/07\/adj-300x211-1.jpg","type":"image\/jpeg"}],"author":"Gente de B\u00e1squet","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gente de B\u00e1squet","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2015\/07\/29\/se-levanto-la-veda\/#article","isPartOf":{"@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2015\/07\/29\/se-levanto-la-veda\/"},"author":{"name":"Gente de B\u00e1squet","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#\/schema\/person\/ca0b63bbb977369988a7bbbdc519943a"},"headline":"Se levant\u00f3 la veda","datePublished":"2015-07-29T18:20:13+00:00","mainEntityOfPage":{"@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2015\/07\/29\/se-levanto-la-veda\/"},"wordCount":753,"image":{"@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2015\/07\/29\/se-levanto-la-veda\/#primaryimage"},"thumbnailUrl":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2015\/07\/adj-300x211-1.jpg","keywords":["AdC","ADJ","LNB","TNA"],"articleSection":["Liga Argentina","Liga Nacional","Nacional"],"inLanguage":"es"},{"@type":"WebPage","@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2015\/07\/29\/se-levanto-la-veda\/","url":"http:\/\/gentedebasquet.com.ar\/sitio\/2015\/07\/29\/se-levanto-la-veda\/","name":"Se levant\u00f3 la veda - Gente de B\u00e1squet","isPartOf":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#website"},"primaryImageOfPage":{"@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2015\/07\/29\/se-levanto-la-veda\/#primaryimage"},"image":{"@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2015\/07\/29\/se-levanto-la-veda\/#primaryimage"},"thumbnailUrl":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2015\/07\/adj-300x211-1.jpg","datePublished":"2015-07-29T18:20:13+00:00","author":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#\/schema\/person\/ca0b63bbb977369988a7bbbdc519943a"},"breadcrumb":{"@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2015\/07\/29\/se-levanto-la-veda\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/gentedebasquet.com.ar\/sitio\/2015\/07\/29\/se-levanto-la-veda\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2015\/07\/29\/se-levanto-la-veda\/#primaryimage","url":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2015\/07\/adj-300x211-1.jpg","contentUrl":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2015\/07\/adj-300x211-1.jpg","width":300,"height":211},{"@type":"BreadcrumbList","@id":"http:\/\/gentedebasquet.com.ar\/sitio\/2015\/07\/29\/se-levanto-la-veda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/gentedebasquet.com.ar\/sitio\/"},{"@type":"ListItem","position":2,"name":"Se levant\u00f3 la veda"}]},{"@type":"WebSite","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#website","url":"https:\/\/gentedebasquet.com.ar\/sitio\/","name":"Gente de B\u00e1squet","description":"La revista del basquet de Bah\u00eda Blanca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gentedebasquet.com.ar\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#\/schema\/person\/ca0b63bbb977369988a7bbbdc519943a","name":"Gente de B\u00e1squet","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","caption":"Gente de B\u00e1squet"},"sameAs":["http:\/\/gentedebasquet.com.ar\/sitio"],"url":"https:\/\/gentedebasquet.com.ar\/sitio\/author\/ulises\/"}]}},"_links":{"self":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/48821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=48821"}],"version-history":[{"count":0,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/48821\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/media\/48844"}],"wp:attachment":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=48821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=48821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=48821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}