{"id":68986,"date":"2017-02-28T23:18:00","date_gmt":"2017-03-01T02:18:00","guid":{"rendered":"http:\/\/www.gentedebasquet.com.ar\/?p=68986"},"modified":"2017-02-28T23:18:00","modified_gmt":"2017-03-01T02:18:00","slug":"entre-la-desazon-y-la-polemica","status":"publish","type":"post","link":"https:\/\/gentedebasquet.com.ar\/sitio\/2017\/02\/28\/entre-la-desazon-y-la-polemica\/","title":{"rendered":"Entre la desaz\u00f3n y la pol\u00e9mica"},"content":{"rendered":"<p><strong>P\u00e9rfora de Plaza Huincul\u00a0revalid\u00f3 su papel de candidato en la Divisi\u00f3n Oeste del TFB al quedarse con un partido dur\u00edsimo frente a Villa Mitre\u00a0por 80 a 79.\u00a0El tricolor, que cerr\u00f3 la gira por Neuqu\u00e9n sin victorias (0\/3) ganaba 77-79 a 14s y debi\u00f3 tener la bola, aunque los jueces se la dieron al local (ver video). All\u00ed, Claris anot\u00f3 doble y falta para ganar el juego. Le restan cuatro partidos\u00a0como local antes de iniciar los playoffs.<\/strong><\/p>\n<p>Fue un partidazo en el Malvinas Argentinas entre el Verde que volv\u00eda a las canchas despu\u00e9s de 8 d\u00edas parado y Villa Mitre que quer\u00eda cerrar la gira por Neuqu\u00e9n con al menos un punto. Los equipos no se sacaron diferencia y el duelo fue de golpe por golpe de principio a fin, pero P\u00e9rfora se mantuvo con la mente fr\u00eda para ganarlo en la \u00faltima bola.<\/p>\n<p>Con parciales de 14-15 y 33-33 los equipos marcharon a los vestuarios con la clara intenci\u00f3n de corregir los baches defensivos, ya que los ataques de ambos lados siempre terminaban en conversiones. Fue en la mitad inicial donde los dos lograron sacarse las mayores diferencias, P\u00e9rfora por 5 puntos (31-26) y Villa Mitre por la misma cifra (15-10), pero el inicio del complemento estuvo cargado de errores de los dos lados y la visita logr\u00f3 una luz de diferencia al cierre del tercer periodo con una buena rotaci\u00f3n de bal\u00f3n y los aciertos de su figura, Jos\u00e9 Guti\u00e9rrez que anot\u00f3 23 puntos.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-67031\" src=\"http:\/\/www.gentedebasquet.com.ar\/wp-content\/uploads\/2016\/11\/Assen-1.jpg\" alt=\"assen\" width=\"640\" height=\"88\" srcset=\"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2016\/11\/Assen-1.jpg 640w, https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2016\/11\/Assen-1-300x41.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>No obstante del lado del local las respuestas aparecieron en la voluntad de Juli\u00e1n Fedele (17 puntos y 5 rebotes) y Javier Ledesma que con 24 puntos fue el goleador y responsable de transmitir seguridad para que el Verde no perdiera los estribos. El periodo concluy\u00f3 en 50-48 para Villa Mitre.<\/p>\n<p>El cuarto final no fue apto para card\u00edacos, con 5 minutos transcurridos en el reloj los equipos igualaban en 59 y Villa Mitre consigui\u00f3 varias penetraciones con faltas de recompensa que lo llevaron a un cierre casi ideal con 4 puntos de ventaja a menos de un minuto (78-74) pero en el final apareci\u00f3 Nacho Claris para llevarse una ovaci\u00f3n. Primero con una gran jugada y un pase con ojos en la espalda para un triple de Fedele y sobre el final con una bandeja que entr\u00f3 con suspenso a falta de 4 segundos y un simple de recompensa para cerrar el tanteador en 80-79 y desatar la euforia en el Malvinas.<\/p>\n<blockquote class=\"twitter-video\" data-lang=\"es\">\n<p dir=\"ltr\" lang=\"es\">Ganaba <a href=\"https:\/\/twitter.com\/VMBasquet\">@VMBasquet<\/a> 79 a 77 y a 14s se produjo esta jugada clave en el desarrollo del partido ? <a href=\"https:\/\/t.co\/us6JAUFnHK\">pic.twitter.com\/us6JAUFnHK<\/a><\/p>\n<p>\u2014 Gente de B\u00e1squet (@GenteDeBasquet) <a href=\"https:\/\/twitter.com\/GenteDeBasquet\/status\/836763461996724229\">1 de marzo de 2017<\/a><\/p><\/blockquote>\n<p><script src=\"\/\/platform.twitter.com\/widgets.js\" async=\"\" charset=\"utf-8\"><\/script><\/p>\n<p>&nbsp;<\/p>\n<p><strong>S\u00edntesis |<\/strong> TFB &#8211;\u00a0Divisi\u00f3n Bonaerense \/ Oeste &#8211; Juego #20<\/p>\n<p><strong>P\u00e9rfora (Plaza Huincul) 80:<\/strong> Juli\u00e1n Fedele 17, Agust\u00edn P\u00e9rez 2, Alejandro Marinelli 0, Javier Ledesma 24, Cristian Scaramuzzino 3 (x) (Fi); Ignacio Claris 7, Fabricio Caba\u00f1as 0, Carlos Sep\u00falveda 15, Agust\u00edn Busso 5 y Leonardo Catelotti 7. DT: Fernando Claris.<\/p>\n<p><strong>Villa Mitre 79:<\/strong> Jos\u00e9 Guti\u00e9rrez 23, Gast\u00f3n Diomedi 11, Cristian Miguel 17, Ramiro Heinrich 9 (x), Javier Bollo 7 (Fi); Mat\u00edas Monteoliva 8, Jos\u00e9 Luis Mart\u00ednez 1 y Bruno Pallotti 3. DT: Ariel Ugolini.<\/p>\n<p><strong>Parciales:<\/strong> 14-15, 33-33 (19-18), 50-48 (17-15) y 80-79 (30-31).<\/p>\n<p><strong>\u00c1rbitros:<\/strong> Gabriel Velazco &#8211; Cristian Carrasco.<\/p>\n<p><a href=\"http:\/\/www.fibalivestats.com\/u\/CAM\/576772\/bs.html\" target=\"_blank\" rel=\"noopener\">ESTAD\u00cdSTICAS OFICIALES<\/a><\/p>\n<p><strong>Fuente:<\/strong> Prensa P\u00e9rfora.<\/p>\n<p><strong>Foto:<\/strong> Prensa P\u00e9rfora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un final dram\u00e1tico, Villa Mitre cay\u00f3 en cancha de P\u00e9rfora (PH) por 80-79<\/p>\n","protected":false},"author":1,"featured_media":68989,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"footnotes":""},"categories":[36,39,101],"tags":[90,426,354,40,22],"class_list":["post-68986","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-federal","category-nacional","category-slide","tag-jose-gutierrez","tag-perfora","tag-tfb","tag-torneo-federal","tag-villa-mitre"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entre la desaz\u00f3n y la pol\u00e9mica - Gente de B\u00e1squet<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gentedebasquet.com.ar\/sitio\/2017\/02\/28\/entre-la-desazon-y-la-polemica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entre la desaz\u00f3n y la pol\u00e9mica - Gente de B\u00e1squet\" \/>\n<meta property=\"og:description\" content=\"En un final dram\u00e1tico, Villa Mitre cay\u00f3 en cancha de P\u00e9rfora (PH) por 80-79\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gentedebasquet.com.ar\/sitio\/2017\/02\/28\/entre-la-desazon-y-la-polemica\/\" \/>\n<meta property=\"og:site_name\" content=\"Gente de B\u00e1squet\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-01T02:18:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2017\/03\/Perfora-Villa-Mitre-TFB.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"690\" \/>\n\t<meta property=\"og:image:height\" content=\"319\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gente de B\u00e1squet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gente de B\u00e1squet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2017\\\/02\\\/28\\\/entre-la-desazon-y-la-polemica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2017\\\/02\\\/28\\\/entre-la-desazon-y-la-polemica\\\/\"},\"author\":{\"name\":\"Gente de B\u00e1squet\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#\\\/schema\\\/person\\\/ca0b63bbb977369988a7bbbdc519943a\"},\"headline\":\"Entre la desaz\u00f3n y la pol\u00e9mica\",\"datePublished\":\"2017-03-01T02:18:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2017\\\/02\\\/28\\\/entre-la-desazon-y-la-polemica\\\/\"},\"wordCount\":557,\"image\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2017\\\/02\\\/28\\\/entre-la-desazon-y-la-polemica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Perfora-Villa-Mitre-TFB.jpg\",\"keywords\":[\"Jos\u00e9 Guti\u00e9rrez\",\"P\u00e9rfora\",\"TFB\",\"Torneo Federal\",\"Villa Mitre\"],\"articleSection\":[\"Federal\",\"Nacional\",\"Slide\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2017\\\/02\\\/28\\\/entre-la-desazon-y-la-polemica\\\/\",\"url\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2017\\\/02\\\/28\\\/entre-la-desazon-y-la-polemica\\\/\",\"name\":\"Entre la desaz\u00f3n y la pol\u00e9mica - Gente de B\u00e1squet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2017\\\/02\\\/28\\\/entre-la-desazon-y-la-polemica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2017\\\/02\\\/28\\\/entre-la-desazon-y-la-polemica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Perfora-Villa-Mitre-TFB.jpg\",\"datePublished\":\"2017-03-01T02:18:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#\\\/schema\\\/person\\\/ca0b63bbb977369988a7bbbdc519943a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2017\\\/02\\\/28\\\/entre-la-desazon-y-la-polemica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2017\\\/02\\\/28\\\/entre-la-desazon-y-la-polemica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2017\\\/02\\\/28\\\/entre-la-desazon-y-la-polemica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Perfora-Villa-Mitre-TFB.jpg\",\"contentUrl\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Perfora-Villa-Mitre-TFB.jpg\",\"width\":690,\"height\":319},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/2017\\\/02\\\/28\\\/entre-la-desazon-y-la-polemica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entre la desaz\u00f3n y la pol\u00e9mica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/\",\"name\":\"Gente de B\u00e1squet\",\"description\":\"La revista del basquet de Bah\u00eda Blanca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/#\\\/schema\\\/person\\\/ca0b63bbb977369988a7bbbdc519943a\",\"name\":\"Gente de B\u00e1squet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"caption\":\"Gente de B\u00e1squet\"},\"sameAs\":[\"http:\\\/\\\/gentedebasquet.com.ar\\\/sitio\"],\"url\":\"https:\\\/\\\/gentedebasquet.com.ar\\\/sitio\\\/author\\\/ulises\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entre la desaz\u00f3n y la pol\u00e9mica - Gente de B\u00e1squet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gentedebasquet.com.ar\/sitio\/2017\/02\/28\/entre-la-desazon-y-la-polemica\/","og_locale":"es_ES","og_type":"article","og_title":"Entre la desaz\u00f3n y la pol\u00e9mica - Gente de B\u00e1squet","og_description":"En un final dram\u00e1tico, Villa Mitre cay\u00f3 en cancha de P\u00e9rfora (PH) por 80-79","og_url":"https:\/\/gentedebasquet.com.ar\/sitio\/2017\/02\/28\/entre-la-desazon-y-la-polemica\/","og_site_name":"Gente de B\u00e1squet","article_published_time":"2017-03-01T02:18:00+00:00","og_image":[{"width":690,"height":319,"url":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2017\/03\/Perfora-Villa-Mitre-TFB.jpg","type":"image\/jpeg"}],"author":"Gente de B\u00e1squet","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gente de B\u00e1squet","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2017\/02\/28\/entre-la-desazon-y-la-polemica\/#article","isPartOf":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2017\/02\/28\/entre-la-desazon-y-la-polemica\/"},"author":{"name":"Gente de B\u00e1squet","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#\/schema\/person\/ca0b63bbb977369988a7bbbdc519943a"},"headline":"Entre la desaz\u00f3n y la pol\u00e9mica","datePublished":"2017-03-01T02:18:00+00:00","mainEntityOfPage":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2017\/02\/28\/entre-la-desazon-y-la-polemica\/"},"wordCount":557,"image":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2017\/02\/28\/entre-la-desazon-y-la-polemica\/#primaryimage"},"thumbnailUrl":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2017\/03\/Perfora-Villa-Mitre-TFB.jpg","keywords":["Jos\u00e9 Guti\u00e9rrez","P\u00e9rfora","TFB","Torneo Federal","Villa Mitre"],"articleSection":["Federal","Nacional","Slide"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2017\/02\/28\/entre-la-desazon-y-la-polemica\/","url":"https:\/\/gentedebasquet.com.ar\/sitio\/2017\/02\/28\/entre-la-desazon-y-la-polemica\/","name":"Entre la desaz\u00f3n y la pol\u00e9mica - Gente de B\u00e1squet","isPartOf":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2017\/02\/28\/entre-la-desazon-y-la-polemica\/#primaryimage"},"image":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2017\/02\/28\/entre-la-desazon-y-la-polemica\/#primaryimage"},"thumbnailUrl":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2017\/03\/Perfora-Villa-Mitre-TFB.jpg","datePublished":"2017-03-01T02:18:00+00:00","author":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#\/schema\/person\/ca0b63bbb977369988a7bbbdc519943a"},"breadcrumb":{"@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2017\/02\/28\/entre-la-desazon-y-la-polemica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gentedebasquet.com.ar\/sitio\/2017\/02\/28\/entre-la-desazon-y-la-polemica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2017\/02\/28\/entre-la-desazon-y-la-polemica\/#primaryimage","url":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2017\/03\/Perfora-Villa-Mitre-TFB.jpg","contentUrl":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-content\/uploads\/2017\/03\/Perfora-Villa-Mitre-TFB.jpg","width":690,"height":319},{"@type":"BreadcrumbList","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/2017\/02\/28\/entre-la-desazon-y-la-polemica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/gentedebasquet.com.ar\/sitio\/"},{"@type":"ListItem","position":2,"name":"Entre la desaz\u00f3n y la pol\u00e9mica"}]},{"@type":"WebSite","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#website","url":"https:\/\/gentedebasquet.com.ar\/sitio\/","name":"Gente de B\u00e1squet","description":"La revista del basquet de Bah\u00eda Blanca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gentedebasquet.com.ar\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gentedebasquet.com.ar\/sitio\/#\/schema\/person\/ca0b63bbb977369988a7bbbdc519943a","name":"Gente de B\u00e1squet","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","caption":"Gente de B\u00e1squet"},"sameAs":["http:\/\/gentedebasquet.com.ar\/sitio"],"url":"https:\/\/gentedebasquet.com.ar\/sitio\/author\/ulises\/"}]}},"_links":{"self":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/68986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=68986"}],"version-history":[{"count":0,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/68986\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/media\/68989"}],"wp:attachment":[{"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=68986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=68986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gentedebasquet.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=68986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}